{"id":4337,"date":"2021-10-18T08:00:41","date_gmt":"2021-10-18T11:00:41","guid":{"rendered":"https:\/\/blog.regionaltelhas.com.br\/?p=4337"},"modified":"2023-08-22T18:05:08","modified_gmt":"2023-08-22T18:05:08","slug":"telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir","status":"publish","type":"post","link":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/","title":{"rendered":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR"},"content":{"rendered":"<p>Durante a constru\u00e7\u00e3o de uma casa, uma das partes mais importantes \u00e9 o telhado, pois ele influencia no conforto t\u00e9rmico e ac\u00fastico no interior do im\u00f3vel. Mesmo para projetos de or\u00e7amento mais baixo, ainda \u00e9 necess\u00e1rio investir bem para entregar o melhor resultado. Para tanto, um dos tipos mais recomendados \u00e9 a telha sandu\u00edche para resid\u00eancia.<\/p>\n<p>Por\u00e9m, mesmo dentro desse tipo, ainda existe uma variedade de modelos de telha, cada um sendo confeccionado com materiais diferentes, que proporcionam distintas qualidades para a pe\u00e7a como um todo. Entender essas particularidades \u00e9 indispens\u00e1vel para entregar o melhor projeto para o cliente.<\/p>\n<p>Para te ajudar a fazer a melhor escolha, separamos aqui algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e quais s\u00e3o as principais diferen\u00e7as entre os modelos EPS e PIR. Acompanhe!<\/p>\n<h2>O que \u00e9 a telha sandu\u00edche?<\/h2>\n<p>Talhas termoac\u00fasticas, tamb\u00e9m chamadas de \u201ctelhas sandu\u00edche\u201d, s\u00e3o pe\u00e7as feitas para proporcionar o m\u00e1ximo de isolamento poss\u00edvel, tanto de som quanto de temperatura. Algo muito \u00fatil para prover o mais alto n\u00edvel de conforto t\u00e9rmico e ac\u00fastico em qualquer resid\u00eancia.<\/p>\n<p>Isso \u00e9 poss\u00edvel devido \u00e0 estrutura caracter\u00edstica da &#8220;telha sandu\u00edche&#8221;. Ela \u00e9 composta por duas\u00a0<a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-de-aco-sanduiche-conheca-3-vantagens\/\" target=\"_blank\" rel=\"noopener noreferrer\">telhas de a\u00e7o<\/a>\u00a0com um material isolante entre ambas, o que proporciona maior efici\u00eancia no bloqueio de sons e diminui a condu\u00e7\u00e3o de calor. Geralmente vem em um formato trapezoidal, que \u00e9 compat\u00edvel com a maioria das estruturas de telhado.<\/p>\n<p>Alguns modelos recebem outros complementos, mas a estrutura b\u00e1sica \u00e9 a mesma. Mesmo que o investimento inicial seja mais alto, a melhora na qualidade de vida ao\u00a0<a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/como-instalar-telha-sanduiche-aprenda-nesse-passo-a-passo\/\" target=\"_blank\" rel=\"noopener noreferrer\">instalar telha sandu\u00edche<\/a>\u00a0compensa muito.<\/p>\n<h2>Quais as diferen\u00e7as entre os modelos EPS e PIR<\/h2>\n<p>Os diferentes modelos de telha sandu\u00edche para resid\u00eancias s\u00e3o baseados no tipo de material de isolamento usado. Confira aqui dois dos principais, o EPS e o PIR, e suas principais diferen\u00e7as.<\/p>\n<h3>Modelo EPS<\/h3>\n<p>O poliestireno expandido (EPS) \u00e9 o material mais comum em telhas termoac\u00fasticas, principalmente devido \u00e0 sua versatilidade. Sua composi\u00e7\u00e3o o torna muito leve, sendo ideal para praticamente todo tipo de estrutura, independente de seu porte. Tamb\u00e9m pode ser fabricado com diferentes n\u00edveis de densidade e tipos de textura, se adequando melhor a diferentes constru\u00e7\u00f5es. Hoje em dia, o EPS tamb\u00e9m \u00e9 usado no interior de paredes, o que o torna uma excelente op\u00e7\u00e3o em praticamente qualquer projeto.<\/p>\n<h3>Modelo PIR<\/h3>\n<p>O poliisocianurato, ou PIR, \u00e9 um tipo de pl\u00e1stico termofixo, similar ao poliuretano, mas com diferentes componentes qu\u00edmicos em sua f\u00f3rmula. Seu potencial como\u00a0<a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-isotermica-onde-pode-ser-usada-e-quais-seus-beneficios\/\" target=\"_blank\" rel=\"noopener noreferrer\">telha isot\u00e9rmica<\/a>\u00a0\u00e9 um dos mais altos, o que \u00e9 excelente para lugares que ficam expostos a altas temperaturas a maior parte do tempo. Devido \u00e0 sua composi\u00e7\u00e3o densa, tamb\u00e9m possui alt\u00edssima resist\u00eancia \u00e0 \u00e1gua e umidade. Como obt\u00e9m alta performance com menos uso de material, tamb\u00e9m \u00e9 uma op\u00e7\u00e3o bem rent\u00e1vel para economizar espa\u00e7o.<\/p>\n<p>Agora que voc\u00ea entende melhor as qualidades de cada tipo de telha sandu\u00edche para resid\u00eancia, pode escolher qual delas usar em seus projetos para entregar mais qualidade ao seu cliente. Lembre-se de levar em conta o porte da estrutura e a melhor rela\u00e7\u00e3o entre custo e benef\u00edcio.<\/p>\n<p>Quer continuar recebendo mais dicas para melhorar seus projetos? Ent\u00e3o curta nossa p\u00e1gina no\u00a0<a href=\"https:\/\/www.facebook.com\/regionaltelhas\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>\u00a0e acompanhe tudo em primeira m\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a constru\u00e7\u00e3o de uma casa, uma das partes mais importantes \u00e9 o telhado, pois ele influencia no conforto t\u00e9rmico e ac\u00fastico no interior do im\u00f3vel. Mesmo para projetos de or\u00e7amento mais baixo, ainda \u00e9 necess\u00e1rio investir bem para entregar o melhor resultado. Para tanto, um dos tipos mais recomendados \u00e9 a telha sandu\u00edche para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4338,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[5,6],"tags":[],"class_list":["post-4337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cobertura","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR<\/title>\n<meta name=\"description\" content=\"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR\" \/>\n<meta property=\"og:description\" content=\"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Regional Telhas\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-18T11:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-22T18:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"regionaltelhas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"regionaltelhas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\"},\"author\":{\"name\":\"regionaltelhas\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8\"},\"headline\":\"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR\",\"datePublished\":\"2021-10-18T11:00:41+00:00\",\"dateModified\":\"2023-08-22T18:05:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\"},\"wordCount\":595,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg\",\"articleSection\":[\"Cobertura\",\"Dicas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\",\"name\":\"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR\",\"isPartOf\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg\",\"datePublished\":\"2021-10-18T11:00:41+00:00\",\"dateModified\":\"2023-08-22T18:05:08+00:00\",\"description\":\"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg\",\"contentUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg\",\"width\":1024,\"height\":681,\"caption\":\"telha sandu\u00edche para resid\u00eancia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#website\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\",\"name\":\"Blog Regional Telhas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.regionaltelhas.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\",\"name\":\"Blog Regional Telhas\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png\",\"contentUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png\",\"width\":177,\"height\":72,\"caption\":\"Blog Regional Telhas\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8\",\"name\":\"regionaltelhas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"regionaltelhas\"},\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/author\/regionaltelhas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR","description":"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/","og_locale":"pt_BR","og_type":"article","og_title":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR","og_description":"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!","og_url":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/","og_site_name":"Blog Regional Telhas","article_published_time":"2021-10-18T11:00:41+00:00","article_modified_time":"2023-08-22T18:05:08+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg","type":"image\/jpeg"}],"author":"regionaltelhas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"regionaltelhas","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#article","isPartOf":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/"},"author":{"name":"regionaltelhas","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8"},"headline":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR","datePublished":"2021-10-18T11:00:41+00:00","dateModified":"2023-08-22T18:05:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/"},"wordCount":595,"commentCount":0,"publisher":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg","articleSection":["Cobertura","Dicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/","url":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/","name":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR","isPartOf":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg","datePublished":"2021-10-18T11:00:41+00:00","dateModified":"2023-08-22T18:05:08+00:00","description":"Para te ajudar, separamos algumas informa\u00e7\u00f5es sobre a telha sandu\u00edche para resid\u00eancia e as principais diferen\u00e7as entre os modelos EPS e PIR!","breadcrumb":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#primaryimage","url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg","contentUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2021\/11\/regionaltelhas_regionaltelhas_image_9-min.jpeg","width":1024,"height":681,"caption":"telha sandu\u00edche para resid\u00eancia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/telha-sanduiche-para-residencia-saiba-mais-sobre-os-modelos-eps-e-pir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.regionaltelhas.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Telha sandu\u00edche para resid\u00eancia: saiba mais sobre os modelos EPS e PIR"}]},{"@type":"WebSite","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#website","url":"https:\/\/www.regionaltelhas.com.br\/blog\/","name":"Blog Regional Telhas","description":"","publisher":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.regionaltelhas.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization","name":"Blog Regional Telhas","url":"https:\/\/www.regionaltelhas.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png","contentUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png","width":177,"height":72,"caption":"Blog Regional Telhas"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8","name":"regionaltelhas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"regionaltelhas"},"url":"https:\/\/www.regionaltelhas.com.br\/blog\/author\/regionaltelhas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/4337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4337"}],"version-history":[{"count":3,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/4337\/revisions"}],"predecessor-version":[{"id":5076,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/4337\/revisions\/5076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/media\/4338"}],"wp:attachment":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}