{"id":1593,"date":"2020-03-23T08:00:57","date_gmt":"2020-03-23T11:00:57","guid":{"rendered":"http:\/\/motley-superficial-find.blogs.rockstage.io\/?p=1593"},"modified":"2023-08-22T17:09:51","modified_gmt":"2023-08-22T17:09:51","slug":"como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui","status":"publish","type":"post","link":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/","title":{"rendered":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui"},"content":{"rendered":"<p>A gest\u00e3o da qualidade na constru\u00e7\u00e3o civil \u00e9 um conceito que surgiu para elevar os padr\u00f5es das constru\u00e7\u00f5es, desde a parte do planejamento do empreendimento at\u00e9 a entrega ao cliente. Oferecer um produto de qualidade n\u00e3o impacta apenas a satisfa\u00e7\u00e3o dos consumidores, mas tamb\u00e9m gera economia, organiza\u00e7\u00e3o e a diminui\u00e7\u00e3o de retrabalho e de atrasos, que s\u00e3o os principais problemas encontrados nos canteiros de obra.<\/p>\n<p>Quando os procedimentos e servi\u00e7os s\u00e3o devidamente acompanhados e a equipe segue um padr\u00e3o de produ\u00e7\u00e3o, utilizando os <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/aprenda-a-fazer-a-armazenagem-de-materiais-de-construcao-corretamente\/\" target=\"_blank\" rel=\"noopener noreferrer\">materiais<\/a> da melhor maneira, ocorre a diminui\u00e7\u00e3o do desperd\u00edcio de tempo e de recursos, o que aumenta a produtividade e a qualidade da constru\u00e7\u00e3o.<\/p>\n<p>Se voc\u00ea quer saber mais sobre gest\u00e3o da qualidade na constru\u00e7\u00e3o civil e quais s\u00e3o os seus benef\u00edcios, continue a leitura deste artigo que preparamos para voc\u00ea!<\/p>\n<h2>Qual \u00e9 a import\u00e2ncia da gest\u00e3o da qualidade no canteiro de obras?<\/h2>\n<p>A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Ela \u00e9 amplamente utilizada como um instrumento para atender as expectativas dos consumidores quanto aos servi\u00e7os oferecidos por determinada empresa.<\/p>\n<p>Existem normas que auxiliam a elabora\u00e7\u00e3o e aplica\u00e7\u00e3o de um bom controle de qualidade, como a ISO 9001 \u2014 <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/certificado-de-qualidade-como-escolher-um-fornecedor-para-construcao-civil\/\" target=\"_blank\" rel=\"noopener noreferrer\">certifica\u00e7\u00e3o <\/a>que garante os mais altos n\u00edveis do sistema de gest\u00e3o de qualidade, com reconhecimento nacional e internacional.<\/p>\n<p>Ter um bom controle de qualidade em uma obra garante que todas as atividades ser\u00e3o feitas de maneira <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/saiba-por-que-voce-deveria-usar-concreto-sustentavel-nas-obras\/\" target=\"_blank\" rel=\"noopener noreferrer\">sustent\u00e1vel<\/a>, com o melhor uso dos insumos e recursos, al\u00e9m de aumentar a produtividade dos trabalhadores sem prejudicar sua sa\u00fade e seguran\u00e7a.<\/p>\n<h2>Quais s\u00e3o os benef\u00edcios dessa ferramenta?<\/h2>\n<p>A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil traz vantagens para as empresas de constru\u00e7\u00e3o, que podem diminuir seus custos e prazos, mas tamb\u00e9m para os consumidores, que v\u00e3o usufruir de um <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/como-determinar-a-viabilidade-economica-de-um-empreendimento\/\" target=\"_blank\" rel=\"noopener noreferrer\">empreendimento<\/a> de alto padr\u00e3o.<\/p>\n<p>Confira agora quais s\u00e3o os principais benef\u00edcios do controle da qualidade.<\/p>\n<h3>Redu\u00e7\u00e3o de custos e desperd\u00edcios<\/h3>\n<p>Apesar de exigir alguns investimentos, a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil torna a <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/qual-a-importancia-e-como-fazer-o-diario-de-obras\/\" target=\"_blank\" rel=\"noopener noreferrer\">obra<\/a> mais eficaz quando identifica e aprimora todos os processos produtivos e fluxos que envolvem os consumidores, os fornecedores e os parceiros. Al\u00e9m disso, monitorar o andamento das atividades reduz as chances de erros, retrabalhos e desperd\u00edcio de tempo e de recursos.<\/p>\n<h3>Aumento da produtividade<\/h3>\n<p>Para ter uma boa gest\u00e3o de qualidade, a organiza\u00e7\u00e3o deve atender a uma s\u00e9rie de normas t\u00e9cnicas, que s\u00e3o elaboradas para garantir um certo padr\u00e3o do produto final e para definir as tarefas que cabem a cada colaborador. Isso faz com que os pontos fracos e gargalos da produ\u00e7\u00e3o sejam identificados, o que aumenta a produtividade e uniformiza os servi\u00e7os.<\/p>\n<h3>Efici\u00eancia no controle de processos<\/h3>\n<p>A gest\u00e3o da qualidade na <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/qual-a-importancia-do-isolamento-termico-nos-projetos-de-construcao\/\" target=\"_blank\" rel=\"noopener noreferrer\">constru\u00e7\u00e3o civil<\/a> visa mapear e documentar toda a produ\u00e7\u00e3o, o que possibilita uma vis\u00e3o clara das caracter\u00edsticas mais fortes e dos desafios que a organiza\u00e7\u00e3o enfrentar\u00e1 para aumentar o seu desempenho. Por esse motivo, o controle de processos \u00e9 uma \u00f3tima forma de melhorar a performance do neg\u00f3cio, impactando a satisfa\u00e7\u00e3o dos clientes e a competitividade no mercado.<\/p>\n<p>No mais, o controle de processos faz com que as experi\u00eancias de cada trabalhador sejam repassadas para os demais integrantes da equipe, evitando que o afastamento de um colaborador prejudique o andamento da produ\u00e7\u00e3o. Isso tamb\u00e9m impede que o conhecimento t\u00e9cnico se perca e facilita o treinamento de outras pessoas para a mesma fun\u00e7\u00e3o.<\/p>\n<h2>Como fazer a gest\u00e3o da qualidade?<\/h2>\n<p>A gest\u00e3o da qualidade na constru\u00e7\u00e3o civil deve come\u00e7ar com a avalia\u00e7\u00e3o dos atuais processos e atividades da construtora. Provavelmente, algum controle de qualidade j\u00e1 deve existir em algum n\u00edvel, mesmo que de maneira informal e inconsciente. No entanto, \u00e9 necess\u00e1rio saber quais s\u00e3o os principais pontos que precisam ser melhorados para aumentar o padr\u00e3o dos servi\u00e7os.<\/p>\n<p>Depois dessa avalia\u00e7\u00e3o, deve-se definir o sistema de gest\u00e3o de qualidade e as prioridades da empresa para o futuro, elegendo os respons\u00e1veis por cada etapa e os principais t\u00f3picos que ser\u00e3o abordados. Essa fase \u00e9 seguida pela determina\u00e7\u00e3o das metas e seus indicadores.<\/p>\n<p>As metas s\u00e3o relacionadas \u00e0 obten\u00e7\u00e3o da qualidade em si, mas tamb\u00e9m aos objetivos que precisam ser alcan\u00e7ados por meio do controle dos processos. J\u00e1 os indicadores s\u00e3o os respons\u00e1veis por confirmar se a meta est\u00e1 sendo atingida. Por exemplo, se a meta \u00e9 aumentar a produtividade da equipe, o indicador pode ser a compara\u00e7\u00e3o entre o volume de produ\u00e7\u00e3o anterior e a produtividade depois da gest\u00e3o da qualidade.<\/p>\n<p>Com as metas e os indicadores estabelecidos, \u00e9 poss\u00edvel prosseguir para a realiza\u00e7\u00e3o de treinamentos e a busca de melhorias para os pontos fracos encontrados. A qualidade na constru\u00e7\u00e3o civil n\u00e3o acontece da noite para o dia, sendo necess\u00e1rios investimentos na capacita\u00e7\u00e3o dos trabalhadores e gestores do neg\u00f3cio.<\/p>\n<p>Al\u00e9m disso, \u00e9 essencial informar a import\u00e2ncia da gest\u00e3o da qualidade para que as novas recomenda\u00e7\u00f5es sejam seguidas pelos funcion\u00e1rios. O ideal \u00e9 que todos os servi\u00e7os sejam padronizados executados de maneira semelhante.<\/p>\n<p>Uma boa maneira de ter certeza de que tudo est\u00e1 de acordo com o planejado no sistema de gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 a realiza\u00e7\u00e3o de auditorias. Elas devem acontecer periodicamente e abordar todos os detalhes poss\u00edveis, analisando o que tem sido feito e gerando um relat\u00f3rio com as sugest\u00f5es de melhorias que surgirem.<\/p>\n<p>Por fim, o controle de qualidade deve sempre passar por revis\u00f5es, e o acompanhamento dos processos \u00e9 de extrema import\u00e2ncia nesse caso. Alguns detalhes como a escolha da m\u00e3o de obra e dos materiais que ser\u00e3o utilizados no empreendimento podem fazer toda a diferen\u00e7a no resultado final. Por isso, n\u00e3o deixe de dar aten\u00e7\u00e3o para todos os setores e fases da constru\u00e7\u00e3o.<\/p>\n<p>A gest\u00e3o da qualidade na constru\u00e7\u00e3o civil tem o poder de eliminar problemas ao diminuir os desperd\u00edcios, aumentar a produ\u00e7\u00e3o e <a href=\"https:\/\/www.regionaltelhas.com.br\/blog\/6-dicas-essenciais-para-fazer-a-gestao-de-custos-na-construcao-civil\/\" target=\"_blank\" rel=\"noopener noreferrer\">reduzir os custos<\/a>. Com isso, \u00e9 poss\u00edvel se ater ao cronograma, garantir uma boa coloca\u00e7\u00e3o no mercado e fornecer um empreendimento de qualidade aos consumidores.<\/p>\n<p>Se voc\u00ea gostou deste conte\u00fado, compartilhe este conte\u00fado em suas redes sociais e deixe seus amigos de profiss\u00e3o por dentro do assunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o da qualidade na constru\u00e7\u00e3o civil \u00e9 um conceito que surgiu para elevar os padr\u00f5es das constru\u00e7\u00f5es, desde a parte do planejamento do empreendimento at\u00e9 a entrega ao cliente. Oferecer um produto de qualidade n\u00e3o impacta apenas a satisfa\u00e7\u00e3o dos consumidores, mas tamb\u00e9m gera economia, organiza\u00e7\u00e3o e a diminui\u00e7\u00e3o de retrabalho e de atrasos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-1593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui<\/title>\n<meta name=\"description\" content=\"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui\" \/>\n<meta property=\"og:description\" content=\"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Regional Telhas\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T11:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-22T17:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"regionaltelhas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"regionaltelhas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\"},\"author\":{\"name\":\"regionaltelhas\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8\"},\"headline\":\"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui\",\"datePublished\":\"2020-03-23T11:00:57+00:00\",\"dateModified\":\"2023-08-22T17:09:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\"},\"wordCount\":1142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg\",\"articleSection\":[\"Gest\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\",\"name\":\"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui\",\"isPartOf\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg\",\"datePublished\":\"2020-03-23T11:00:57+00:00\",\"dateModified\":\"2023-08-22T17:09:51+00:00\",\"description\":\"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg\",\"contentUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg\",\"width\":724,\"height\":483,\"caption\":\"Construction. Shallow DOF. Developed from RAW; retouched with special care and attention; Small amount of grain added for best final impression. 16 bit Adobe RGB color profile.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#website\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\",\"name\":\"Blog Regional Telhas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.regionaltelhas.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#organization\",\"name\":\"Blog Regional Telhas\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png\",\"contentUrl\":\"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png\",\"width\":177,\"height\":72,\"caption\":\"Blog Regional Telhas\"},\"image\":{\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8\",\"name\":\"regionaltelhas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"regionaltelhas\"},\"url\":\"https:\/\/www.regionaltelhas.com.br\/blog\/author\/regionaltelhas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui","description":"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/","og_locale":"pt_BR","og_type":"article","og_title":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui","og_description":"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.","og_url":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/","og_site_name":"Blog Regional Telhas","article_published_time":"2020-03-23T11:00:57+00:00","article_modified_time":"2023-08-22T17:09:51+00:00","og_image":[{"width":724,"height":483,"url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg","type":"image\/jpeg"}],"author":"regionaltelhas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"regionaltelhas","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#article","isPartOf":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/"},"author":{"name":"regionaltelhas","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8"},"headline":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui","datePublished":"2020-03-23T11:00:57+00:00","dateModified":"2023-08-22T17:09:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/"},"wordCount":1142,"commentCount":0,"publisher":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg","articleSection":["Gest\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/","url":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/","name":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui","isPartOf":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg","datePublished":"2020-03-23T11:00:57+00:00","dateModified":"2023-08-22T17:09:51+00:00","description":"A gest\u00e3o de qualidade na constru\u00e7\u00e3o civil \u00e9 uma ferramenta que busca padronizar os processos e servi\u00e7os para melhorar a produtividade e o resultado final dos empreendimentos. Acesso nosso artigo e continue a leitura.","breadcrumb":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#primaryimage","url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg","contentUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2020\/03\/GettyImages-618947242.jpg","width":724,"height":483,"caption":"Construction. Shallow DOF. Developed from RAW; retouched with special care and attention; Small amount of grain added for best final impression. 16 bit Adobe RGB color profile."},{"@type":"BreadcrumbList","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/como-fazer-a-gestao-da-qualidade-na-construcao-civil-entenda-aqui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.regionaltelhas.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como fazer a gest\u00e3o da qualidade na constru\u00e7\u00e3o civil? Entenda aqui"}]},{"@type":"WebSite","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#website","url":"https:\/\/www.regionaltelhas.com.br\/blog\/","name":"Blog Regional Telhas","description":"","publisher":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.regionaltelhas.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#organization","name":"Blog Regional Telhas","url":"https:\/\/www.regionaltelhas.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png","contentUrl":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-content\/uploads\/2023\/02\/logo.png","width":177,"height":72,"caption":"Blog Regional Telhas"},"image":{"@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/00100708487f9119fa0006bd4b8ce5e8","name":"regionaltelhas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.regionaltelhas.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"regionaltelhas"},"url":"https:\/\/www.regionaltelhas.com.br\/blog\/author\/regionaltelhas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1593"}],"version-history":[{"count":7,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593\/revisions"}],"predecessor-version":[{"id":5051,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/posts\/1593\/revisions\/5051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/media\/1594"}],"wp:attachment":[{"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regionaltelhas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}